{"id":6018,"date":"2018-11-13T17:04:20","date_gmt":"2018-11-13T17:04:20","guid":{"rendered":"http:\/\/oliveirobra.dotpro.pt\/obras\/brex-revestimentos-e-isolamentos\/"},"modified":"2019-02-21T17:48:27","modified_gmt":"2019-02-21T17:48:27","slug":"brex-revestimentos-e-isolamentos","status":"publish","type":"dt_portfolio","link":"https:\/\/oliveirobra.pt\/en\/obras\/brex-revestimentos-e-isolamentos\/","title":{"rendered":"Brex &#8211; Revestimentos e Isolamentos"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row margin_top=&#8221;-25px&#8221;][vc_column width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1550709903811{padding-left: 0px !important;}&#8221;][vc_row_inner css=&#8221;.vc_custom_1550709913399{padding-left: 0px !important;}&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_icon icon_fontawesome=&#8221;fa fa-building-o&#8221; color=&#8221;black&#8221; size=&#8221;lg&#8221; align=&#8221;right&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;]<div class=\"uavc-list-icon uavc-list-icon-wrapper ult-adjust-bottom-margin   \"><ul class=\"uavc-list\"><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-3419\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:25px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#ab2328;font-size:14px;display:inline-block;\">\n\t<i class=\"Defaults-arrows\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-3419 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"font-weight:bold;color:#ab2328;\">1000 M\u00b2<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-7051\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:25px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:14px;display:inline-block;\">\n\t<i class=\"Defaults-slack\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-7051 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Metallic Structure<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-8043\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:25px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:14px;display:inline-block;\">\n\t<i class=\"Defaults-chevron-up\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-8043 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Roofing<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-4215\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:25px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:14px;display:inline-block;\">\n\t<i class=\"Defaults-cube\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-4215 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Coating<\/span><\/div><\/li><\/ul><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_row_inner css=&#8221;.vc_custom_1550710733370{margin-bottom: -25px !important;}&#8221;][vc_column_inner width=&#8221;1\/4&#8243;][vc_icon icon_fontawesome=&#8221;fa fa-globe&#8221; color=&#8221;black&#8221; size=&#8221;lg&#8221; align=&#8221;right&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<h5>LOCATION<\/h5>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1550713139848{margin-top: -25px !important;}&#8221;]<\/p>\n<p>Famalic\u00e3o<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_icon icon_fontawesome=&#8221;fa fa-calendar&#8221; color=&#8221;black&#8221; size=&#8221;lg&#8221; align=&#8221;right&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<h5>CONCLUSION<\/h5>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1550713150863{margin-top: -25px !important;}&#8221;]<\/p>\n<p>June&nbsp;2018<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_section full_width=&#8221;stretch_row&#8221;][\/vc_section][vc_row type=&#8221;vc_default&#8221; full_width=&#8221;stretch_row_content&#8221;][vc_column][vc_media_grid element_width=&#8221;3&#8243; gap=&#8221;0&#8243; grid_id=&#8221;vc_gid:1550771255134-89bffbc0-3b7b-7&#8243; include=&#8221;2884,2885,2886,2887,3171,2888,3173,5097,5105,5109,5101&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vila Nova de Famalic\u00e3o &#8211; Portugal<\/p>\n","protected":false},"author":2,"featured_media":5106,"template":"","dt_portfolio_category":[121],"dt_portfolio_tags":[],"class_list":["post-6018","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-commerce-and-services","dt_portfolio_category-121","description-off"],"_links":{"self":[{"href":"https:\/\/oliveirobra.pt\/en\/wp-json\/wp\/v2\/dt_portfolio\/6018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oliveirobra.pt\/en\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/oliveirobra.pt\/en\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/oliveirobra.pt\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/oliveirobra.pt\/en\/wp-json\/wp\/v2\/dt_portfolio\/6018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oliveirobra.pt\/en\/wp-json\/wp\/v2\/media\/5106"}],"wp:attachment":[{"href":"https:\/\/oliveirobra.pt\/en\/wp-json\/wp\/v2\/media?parent=6018"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/oliveirobra.pt\/en\/wp-json\/wp\/v2\/dt_portfolio_category?post=6018"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/oliveirobra.pt\/en\/wp-json\/wp\/v2\/dt_portfolio_tags?post=6018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}