{"id":5847,"date":"2018-11-14T18:17:07","date_gmt":"2018-11-14T18:17:07","guid":{"rendered":"http:\/\/oliveirobra.dotpro.pt\/obras\/gardengate\/"},"modified":"2023-03-31T07:57:09","modified_gmt":"2023-03-31T07:57:09","slug":"gardengate","status":"publish","type":"dt_portfolio","link":"https:\/\/oliveirobra.pt\/fr\/obras\/gardengate\/","title":{"rendered":"Gardengate"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row margin_top=\u00a0\u00bb-25px\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1550709903811{padding-left: 0px !important;}\u00a0\u00bb][vc_row_inner css=\u00a0\u00bb.vc_custom_1550709913399{padding-left: 0px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb1\/4&Prime;][vc_icon icon_fontawesome=\u00a0\u00bbfa fa-building-o\u00a0\u00bb color=\u00a0\u00bbblack\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb align=\u00a0\u00bbright\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb3\/4&Prime;]<div class=\"uavc-list-icon uavc-list-icon-wrapper ult-adjust-bottom-margin   \"><ul class=\"uavc-list\"><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-6016\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:25px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#ab2328;font-size:14px;display:inline-block;\">\n\t<i class=\"Defaults-arrows\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-6016 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"font-weight:bold;color:#ab2328;\">3400 M\u00b2<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-6876\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:25px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:14px;display:inline-block;\">\n\t<i class=\"Defaults-slack\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-6876 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Structure M\u00e9tallique<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-1679\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:25px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:14px;display:inline-block;\">\n\t<i class=\"Defaults-chevron-up\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-1679 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Couverture<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-8908\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:25px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:14px;display:inline-block;\">\n\t<i class=\"Defaults-cube\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-8908 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\">Rev\u00eatement<\/span><\/div><\/li><\/ul><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_row_inner css=\u00a0\u00bb.vc_custom_1550710733370{margin-bottom: -25px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb1\/4&Prime;][vc_icon icon_fontawesome=\u00a0\u00bbfa fa-globe\u00a0\u00bb color=\u00a0\u00bbblack\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb align=\u00a0\u00bbright\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb3\/4&Prime;][vc_column_text]<\/p>\n<h5>LOCALIZATION<\/h5>\n<p>[\/vc_column_text][vc_column_text css=\u00a0\u00bb.vc_custom_1550711838377{margin-top: -25px !important;}\u00a0\u00bb]<\/p>\n<p>Braga<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/4&Prime;][vc_icon icon_fontawesome=\u00a0\u00bbfa fa-calendar\u00a0\u00bb color=\u00a0\u00bbblack\u00a0\u00bb size=\u00a0\u00bblg\u00a0\u00bb align=\u00a0\u00bbright\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb3\/4&Prime;][vc_column_text]<\/p>\n<h5>CONCLUSION<\/h5>\n<p>[\/vc_column_text][vc_column_text css=\u00a0\u00bb.vc_custom_1550710658931{margin-top: -25px !important;}\u00a0\u00bb]<\/p>\n<p>En cours<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00a0\u00bbvc_default\u00a0\u00bb full_width=\u00a0\u00bbstretch_row_content\u00a0\u00bb][vc_column][vc_media_grid element_width=\u00a0\u00bb3&Prime; gap=\u00a0\u00bb0&Prime; grid_id=\u00a0\u00bbvc_gid:1550762513550-e74d4049-374f-3&Prime; include=\u00a0\u00bb3098,3195,4717,4725,4721,5084,5088,5092&Prime;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Figueiredo &#8211; Braga &#8211; Portugal<\/p>\n","protected":false},"author":2,"featured_media":5086,"template":"","dt_portfolio_category":[118],"dt_portfolio_tags":[],"class_list":["post-5847","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-industriel","dt_portfolio_category-118","description-off"],"_links":{"self":[{"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/dt_portfolio\/5847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/dt_portfolio\/5847\/revisions"}],"predecessor-version":[{"id":6735,"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/dt_portfolio\/5847\/revisions\/6735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/media\/5086"}],"wp:attachment":[{"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/media?parent=5847"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/dt_portfolio_category?post=5847"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/oliveirobra.pt\/fr\/wp-json\/wp\/v2\/dt_portfolio_tags?post=5847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}